{"id":1806,"date":"2012-07-16T14:56:56","date_gmt":"2012-07-16T12:56:56","guid":{"rendered":"http:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR.jpg"},"modified":"2012-07-16T14:56:56","modified_gmt":"2012-07-16T12:56:56","slug":"toivolepikdeerr-2","status":"inherit","type":"attachment","link":"https:\/\/www.estonianwildlifetours.com\/de\/toivolepikdeerr-2\/","title":{"rendered":"Foto:ToivoLepik.Reddeer"},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"class_list":["post-1806","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-300x200.jpg 300w, https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-1024x682.jpg 1024w, https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-768x512.jpg 768w, https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":853,"file":"2012\/06\/ToivoLepikdeerR.jpg","filesize":207138,"sizes":{"medium":{"file":"ToivoLepikdeerR-300x200.jpg","width":300,"height":200,"filesize":16704,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-300x200.jpg"},"large":{"file":"ToivoLepikdeerR-1024x682.jpg","width":1024,"height":682,"filesize":138278,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-1024x682.jpg"},"thumbnail":{"file":"ToivoLepikdeerR-150x150.jpg","width":150,"height":150,"filesize":8201,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-150x150.jpg"},"medium_large":{"file":"ToivoLepikdeerR-768x512.jpg","width":768,"height":512,"filesize":83935,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-768x512.jpg"},"thumb300":{"file":"ToivoLepikdeerR-300x200.jpg","width":300,"height":200,"filesize":16704,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-300x200.jpg"},"post-thumbnail":{"file":"ToivoLepikdeerR-940x198.jpg","width":940,"height":198,"filesize":47193,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR-940x198.jpg"},"full":{"file":"ToivoLepikdeerR.jpg","width":1280,"height":853,"mime_type":"image\/jpeg","source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"Canon EOS-1D Mark III","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/ToivoLepikdeerR.jpg","_links":{"self":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/media\/1806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/comments?post=1806"}]}}