{"id":1796,"date":"2012-07-13T20:06:37","date_gmt":"2012-07-13T18:06:37","guid":{"rendered":"http:\/\/www.estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing.jpg"},"modified":"2012-07-13T20:06:37","modified_gmt":"2012-07-13T18:06:37","slug":"podertonuling-3","status":"inherit","type":"attachment","link":"https:\/\/www.estonianwildlifetours.com\/de\/podertonuling-3\/","title":{"rendered":"Elk\/Moose.Foto:T\u00f5nuLing"},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":{"_acf_changed":false},"class_list":["post-1796","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-300x200.jpg 300w, https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":400,"file":"2012\/06\/PoderT\u00f5nuLing.jpg","filesize":176095,"sizes":{"medium":{"file":"PoderT\u00f5nuLing-300x200.jpg","width":300,"height":200,"filesize":51275,"mime_type":"image\/jpeg","source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-300x200.jpg"},"thumbnail":{"file":"PoderT\u00f5nuLing-150x150.jpg","width":150,"height":150,"filesize":40456,"mime_type":"image\/jpeg","source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-150x150.jpg"},"thumb300":{"file":"PoderT\u00f5nuLing-300x200.jpg","width":300,"height":200,"filesize":51275,"mime_type":"image\/jpeg","source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-300x200.jpg"},"post-thumbnail":{"file":"PoderT\u00f5nuLing-600x198.jpg","width":600,"height":198,"filesize":71123,"mime_type":"image\/jpeg","source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing-600x198.jpg"},"full":{"file":"PoderT\u00f5nuLing.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing.jpg"}},"image_meta":{"aperture":"5.6","credit":"T\u00f5nu Ling","camera":"Canon EOS 40D","caption":"","created_timestamp":"1190627866","copyright":"T\u00f5nu Ling \u00a9 2007","focal_length":"400","iso":"400","shutter_speed":"0.0015625","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/estonianwildlifetours.com\/wp-content\/uploads\/2012\/06\/PoderT\u00f5nuLing.jpg","_links":{"self":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/media\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estonianwildlifetours.com\/de\/wp-json\/wp\/v2\/comments?post=1796"}]}}